{"id":3371,"date":"2026-03-17T12:09:27","date_gmt":"2026-03-17T11:09:27","guid":{"rendered":"https:\/\/www.footclubs.be\/kosova\/?post_type=news&#038;p=3371"},"modified":"2026-03-17T12:09:27","modified_gmt":"2026-03-17T11:09:27","slug":"porsperger-lattaque-lui-va-si-bien","status":"publish","type":"news","link":"https:\/\/www.footclubs.be\/kosova\/news\/porsperger-lattaque-lui-va-si-bien\/","title":{"rendered":"Porsperger, l\u2019attaque lui va si bien"},"content":{"rendered":"<div class=\"para\"><strong>Reda Benslimane<\/strong>, habituel \u00e9l\u00e9ment le plus avanc\u00e9 de l\u2019\u00e9chiquier schaerbeekois, s\u2019est occasionn\u00e9 une luxation de l\u2019\u00e9paule \u00e0 la suite d\u2019un contact \u00e0 l\u2019entra\u00eenement de mardi pass\u00e9. L\u2019int\u00e9ress\u00e9 attend encore de conna\u00eetre la dur\u00e9e de son indisponibilit\u00e9. Pour pallier cette absence, le staff a fait le choix de titulariser <strong>Ethan Porsperger<\/strong>. Face \u00e0 <strong>Aische<\/strong>, l\u2019ancien joueur du <strong>Stade Everois<\/strong> ou encore du <strong>Suryoy\u00e9s Bruxellois<\/strong> a donc \u00e9volu\u00e9 dans un r\u00f4le inhabituel d\u2019attaquant de pointe. <strong>\u00ab\u00a0Ce n\u2019est pas une position \u00e0 laquelle j\u2019ai l\u2019habitude d\u2019\u00e9voluer, mais comme chaque \u00e9l\u00e9ment du vestiaire je suis pr\u00eat \u00e0 tout pour aider l\u2019\u00e9quipe. Le staff a op\u00e9r\u00e9 ce choix et j\u2019ai tent\u00e9 de rendre la confiance t\u00e9moign\u00e9e. Le staff a l\u2019habitude de devoir composer avec les absences et nos entra\u00eeneurs aiment essayer certains \u00e9l\u00e9ments sur certains postes lorsque cela s\u2019av\u00e8re n\u00e9cessaire. Ce n\u2019est pas quelque chose de nouveau au sein du vestiaire et chacun tente d\u2019apporter \u00e0 la prestation collective peu importe la position occup\u00e9e sur le terrain. Ce fonctionnement porte ses fruits lorsque l\u2019on regarde notre parcours et notamment notre succ\u00e8s de ce week-end. Notre polyvalence est une vraie force\u00a0\u00bb<\/strong>, confie <strong>Ethan Porsperger<\/strong> qui a marqu\u00e9 le 1-0 face \u00e0 <strong>Aische<\/strong>.<\/div>\n<div class=\"subhead\">\n<h3 class=\"para\">R\u00e9flexe d\u2019attaquant<\/h3>\n<\/div>\n<div class=\"para\">Sur son but qui a permis au <strong>Kosova<\/strong> de prendre les commandes face \u00e0 <strong>Aische<\/strong>, le jeune joueur <strong>n\u00e9 en 2005<\/strong> a bien suivi son co\u00e9quipier <strong>Younes Zibouh<\/strong> parti au but. <strong>\u00ab\u00a0C\u2019\u00e9tait un r\u00e9flexe d\u2019attaquant\u00a0\u00bb<\/strong>, s\u2019amuse l\u2019int\u00e9ress\u00e9. <strong>\u00ab\u00a0Lorsque je vois Younes filer vers la cage adverse, je me dis que je dois suivre son mouvement. J\u2019ai bien fait puisque sa frappe d\u00e9tourn\u00e9e par le portier adverse retombe dans mes pieds et je parviens \u00e0 glisser au fond. Pour le reste de ma prestation, j\u2019ai tent\u00e9 de peser sur la d\u00e9fense adverse\u00a0\u00bb<\/strong>, explique le joueur qui revenait de blessure. <strong>\u00ab\u00a0J\u2019\u00e9tais sur le flanc depuis un mois et demi \u00e0 cause d\u2019une cheville capricieuse. J\u2019ai pu jouer l\u2019enti\u00e8ret\u00e9 de la rencontre et les sensations \u00e9taient bonnes. J\u2019esp\u00e8re que cela va continuer ainsi.\u00a0\u00bb<\/strong><\/div>\n<div class=\"subhead\">\n<h3 class=\"para\">Finir en beaut\u00e9<\/h3>\n<\/div>\n<div class=\"para\">Avec un avantage cons\u00e9quent sur la zone dangereuse, le <strong>Kosova<\/strong> a quasi assur\u00e9 son objectif de la saison m\u00eame si le maintien n\u2019est pas encore math\u00e9matiquement acquis. <strong>9e<\/strong> du classement \u00e0 six journ\u00e9es de la fin et avec six points de retard sur la 5e place, le groupe schaerbeekois peut regarder vers le haut. <strong>\u00ab\u00a0On n\u2019entend pas finir la saison en roue libre. On va continuer \u00e0 tenter de gagner des rencontres d\u2019ici la fin de la campagne en cours. On a fait un pas suppl\u00e9mentaire vers le maintien, mais on veut surtout regarder la colonne de gauche et pourquoi pas une chance de figurer au tour final. On reste sur trois victoires de rang en championnat (NDLR\u00a0: une premi\u00e8re cette saison), si on garde ce rythme tout est possible. Nous avons encore six matches \u00e0 disputer, on verra o\u00f9 l\u2019on se trouve au moment du d\u00e9compte final, mais notre campagne est d\u00e9j\u00e0 r\u00e9ussie. On va tenter de grappiller dans les semaines \u00e0 l\u2019avenir\u00a0\u00bb<\/strong>, ponctue <strong>Ethan Porsperge<\/strong>r.<\/div>\n<div><\/div>\n<div><\/div>\n<div><strong>par P-A. H.<\/strong> (<strong>Sudinfo.Sports<\/strong>)<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Reda Benslimane, habituel \u00e9l\u00e9ment le plus avanc\u00e9 de l\u2019\u00e9chiquier schaerbeekois, s\u2019est occasionn\u00e9 une luxation de l\u2019\u00e9paule \u00e0 la suite d\u2019un contact \u00e0 l\u2019entra\u00eenement de mardi pass\u00e9. L\u2019int\u00e9ress\u00e9 attend encore de conna\u00eetre la dur\u00e9e de son indisponibilit\u00e9. Pour pallier cette absence, le staff a fait le choix de titulariser Ethan Porsperger. Face \u00e0 Aische, l\u2019ancien joueur [&hellip;]<\/p>\n","protected":false},"template":"","class_list":["post-3371","news","type-news","status-publish","hentry","newscat-homepage","newscat-press"],"_links":{"self":[{"href":"https:\/\/www.footclubs.be\/kosova\/wp-json\/wp\/v2\/api-news\/3371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.footclubs.be\/kosova\/wp-json\/wp\/v2\/api-news"}],"about":[{"href":"https:\/\/www.footclubs.be\/kosova\/wp-json\/wp\/v2\/types\/news"}],"wp:attachment":[{"href":"https:\/\/www.footclubs.be\/kosova\/wp-json\/wp\/v2\/media?parent=3371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}