{"id":3139,"date":"2025-03-26T15:23:53","date_gmt":"2025-03-26T14:23:53","guid":{"rendered":"https:\/\/www.footclubs.be\/kosova\/?post_type=news&#038;p=3139"},"modified":"2025-03-26T15:40:51","modified_gmt":"2025-03-26T14:40:51","slug":"dames-p2-r-c-s-nivellois-a-et-le-fc-kosova-schaerbeek-se-sont-quittees-sur-un-nul-blanc-0-0","status":"publish","type":"news","link":"https:\/\/www.footclubs.be\/kosova\/news\/dames-p2-r-c-s-nivellois-a-et-le-fc-kosova-schaerbeek-se-sont-quittees-sur-un-nul-blanc-0-0\/","title":{"rendered":"Dames P2 : R.C.S Nivellois A et le FC Kosova Schaerbeek se sont quitt\u00e9es sur un nul blanc (0-0)"},"content":{"rendered":"<p><strong>Nivellois :<\/strong> Hallet, Demaret, Gille, Doucy, Benoye, Poncin, Cosyns, Loxhay, Pigeon, Savarino Villena, Carton, Schiepers, Adens, Lassoie, Iraci. Coach : Criquillon<\/p>\n<p><strong>Kosova :<\/strong>\u00a0Jean Villanueva, H\u00e9reng, Wertz, De Ketelaere, Blakaj, Deborsu, Sesum, Croiset, Pinchart, Ninin, Sauvenier. Coach : Mortier<\/p>\n<p><strong>Arbitre : Wassim Maarouf<\/strong><\/p>\n<p>Ce<strong> samedi 22 mars<\/strong>, un match d\u00e9cisif de la <strong>P2 f\u00e9minine<\/strong> opposait le<strong> FC Kosova Schaerbeek<\/strong>, deuxi\u00e8me du classement, au <strong>RCS Nivelles<\/strong>, leader du championnat. D\u00e8s les premi\u00e8res minutes, le ton \u00e9tait donn\u00e9 : Nivelles affichait un niveau impressionnant. Pr\u00e9cises, puissantes et tactiquement solides, elles imposaient un rythme intense. Mais cette fois, le <strong>FC Kosova<\/strong> ne se laissa pas impressionner, contrairement \u00e0 certains matchs pr\u00e9c\u00e9dents. L\u2019objectif \u00e9tait clair : tenir bon pendant 90 minutes et tenter de marquer.<\/p>\n<p>La premi\u00e8re mi-temps fut \u00e9quilibr\u00e9e, avec m\u00eame davantage d\u2019occasions pour le <strong>FC Kosova<\/strong>, mais sans concr\u00e9tisation. Un penalty, siffl\u00e9 assez injustement pour Nivelles apr\u00e8s une faute de main, aurait pu changer le cours du match. Heureusement, la tireuse nivelloise, sans doute d\u00e9stabilis\u00e9e par la gardienne du FC Kosova, <strong>Aga Villanueva<\/strong>, envoya le ballon au-dessus du cadre.<\/p>\n<p>Au retour des vestiaires, la pression de Nivelles s\u2019intensifia, rendant la relance plus compliqu\u00e9e pour le FC Kosova. Pourtant, l\u2019\u00e9quipe fit preuve d\u2019une grande solidarit\u00e9 et d\u2019une d\u00e9termination sans faille pour ne rien l\u00e2cher.<\/p>\n<p>Le match s\u2019acheva sur un nul <strong>0-0<\/strong>, un r\u00e9sultat dont le <strong>FC Kosova<\/strong> peut \u00eatre fier. Mais cette rencontre mit aussi en lumi\u00e8re un axe de progression : mieux g\u00e9rer la remont\u00e9e du ballon sous pression pour, \u00e0 l\u2019avenir, non seulement tenir t\u00eate aux meilleures \u00e9quipes, mais aussi remporter ce type de confrontation.<\/p>\n<p><a href=\"https:\/\/www.footclubs.be\/kosova\/team\/nos-dames\/\">R\u00e9sultats\/Classement<\/a><\/p>\n<p>Article :\u00a0<strong>Marie, Sandy, Aga<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nivellois : Hallet, Demaret, Gille, Doucy, Benoye, Poncin, Cosyns, Loxhay, Pigeon, Savarino Villena, Carton, Schiepers, Adens, Lassoie, Iraci. Coach : Criquillon Kosova :\u00a0Jean Villanueva, H\u00e9reng, Wertz, De Ketelaere, Blakaj, Deborsu, Sesum, Croiset, Pinchart, Ninin, Sauvenier. Coach : Mortier Arbitre : Wassim Maarouf Ce samedi 22 mars, un match d\u00e9cisif de la P2 f\u00e9minine opposait le [&hellip;]<\/p>\n","protected":false},"template":"","class_list":["post-3139","news","type-news","status-publish","hentry","newscat-lastnews","newscat-homepage"],"_links":{"self":[{"href":"https:\/\/www.footclubs.be\/kosova\/wp-json\/wp\/v2\/api-news\/3139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.footclubs.be\/kosova\/wp-json\/wp\/v2\/api-news"}],"about":[{"href":"https:\/\/www.footclubs.be\/kosova\/wp-json\/wp\/v2\/types\/news"}],"wp:attachment":[{"href":"https:\/\/www.footclubs.be\/kosova\/wp-json\/wp\/v2\/media?parent=3139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}