{"id":17,"date":"2019-09-20T12:39:03","date_gmt":"2019-09-20T10:39:03","guid":{"rendered":"https:\/\/www.footclubs.be\/scchelsea\/?post_type=news&#038;p=471"},"modified":"2019-09-20T12:39:03","modified_gmt":"2019-09-20T10:39:03","slug":"nouveau-site-internet-pour-le-club-f-c-torgny-rouvroy","status":"publish","type":"news","link":"https:\/\/www.footclubs.be\/fctorgny\/news\/nouveau-site-internet-pour-le-club-f-c-torgny-rouvroy\/","title":{"rendered":"Nouveau site internet pour le club F.C. Torgny-Rouvroy"},"content":{"rendered":"<h2>Bienvenue sur le nouveau site officiel du club F.C. Torgny-Rouvroy.<\/h2>\n<p>Gr\u00e2ce \u00e0 ce site cr\u00e9\u00e9 avec l&rsquo;outil <a href=\"https:\/\/www.footclubs.be\">FootClubs<\/a>, vous pourrez suivre toute l&rsquo;actualit\u00e9 du club et tout savoir sur ses activit\u00e9s. Vous y trouverez entre autres :<\/p>\n<ul>\n<li>les news r\u00e9centes et les \u00e9v\u00e8nements \u00e0 venir<\/li>\n<li>la pr\u00e9sentation des \u00e9quipes, leurs r\u00e9sultats et leur classement<\/li>\n<li>la pr\u00e9sentation de nos sponsors et autres partenaires<\/li>\n<li>les membres du comit\u00e9 et du staff sportif<strong><br \/>\n<\/strong><\/li>\n<li>nos activit\u00e9s sur les r\u00e9seaux sociaux<\/li>\n<li>nos galeries photos et vid\u00e9os<\/li>\n<li>et bien plus encore &#8230;<\/li>\n<\/ul>\n<blockquote><p><strong><span style=\"color: #000000\">Note aux administrateurs du site<\/span><\/strong><\/p>\n<p>Ceci est un article d&rsquo;exemple cr\u00e9\u00e9 automatiquement, de m\u00eame que les modules affich\u00e9s dans la zone de droite et en bas de page. Rendez-vous respectivement aux rubriques \u00ab Actualit\u00e9s \u00bb et \u00ab Widgets \u00bb du panel d\u2019administration pour les supprimer ou les modifier.<br \/>\nL\u2019\u00e9quipe <strong><span style=\"color: #5cb85c\">Foot<\/span>Clubs<\/strong><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Bienvenue sur le nouveau site officiel du club F.C. Torgny-Rouvroy. Gr\u00e2ce \u00e0 ce site cr\u00e9\u00e9 avec l&rsquo;outil FootClubs, vous pourrez suivre toute l&rsquo;actualit\u00e9 du club et tout savoir sur ses activit\u00e9s. Vous y trouverez entre autres : les news r\u00e9centes et les \u00e9v\u00e8nements \u00e0 venir la pr\u00e9sentation des \u00e9quipes, leurs r\u00e9sultats et leur classement la [&hellip;]<\/p>\n","protected":false},"template":"","class_list":["post-17","news","type-news","status-publish","hentry","newscat-lastnews","newscat-homepage"],"_links":{"self":[{"href":"https:\/\/www.footclubs.be\/fctorgny\/wp-json\/wp\/v2\/api-news\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.footclubs.be\/fctorgny\/wp-json\/wp\/v2\/api-news"}],"about":[{"href":"https:\/\/www.footclubs.be\/fctorgny\/wp-json\/wp\/v2\/types\/news"}],"wp:attachment":[{"href":"https:\/\/www.footclubs.be\/fctorgny\/wp-json\/wp\/v2\/media?parent=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}