{"id":541,"date":"2020-11-05T09:19:46","date_gmt":"2020-11-05T08:19:46","guid":{"rendered":"https:\/\/www.footclubs.be\/cslens\/?post_type=news&#038;p=541"},"modified":"2020-11-05T09:19:46","modified_gmt":"2020-11-05T08:19:46","slug":"news-u8-u10-u12-du-1er-au-15-novembre-2020","status":"publish","type":"news","link":"https:\/\/www.footclubs.be\/cslens\/news\/news-u8-u10-u12-du-1er-au-15-novembre-2020\/","title":{"rendered":"News U8-U10-U12 du 1er au 15 novembre 2020"},"content":{"rendered":"<div dir=\"auto\"><em><strong>Du 1 novembre au 15 novembre:<\/strong><\/em><\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><strong>ENTRAINEMENTS :<\/strong><\/div>\n<div dir=\"auto\">Suite aux derni\u00e8res d\u00e9cisions politiques et sportives, le RCS Lens continuera d&rsquo;assurer les entrainements (mercredi et vendredi) pour les joueurs des cat\u00e9gories U8, U10 et U12, \u00e0 condition qu&rsquo;un nombre suffisant de joueurs assistent aux s\u00e9ances.<\/div>\n<div dir=\"auto\">Nous vous rappelons l&rsquo;importance d&rsquo;avertir le coach de la pr\u00e9sence ou non de votre enfant, afin que celui-ci puisse adapter son entrainement en fonction.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><strong>MATCHS :<\/strong><\/div>\n<div dir=\"auto\">Par mesure de pr\u00e9caution et pour rester dans l&rsquo;esprit des r\u00e8glements sanitaires, nous ne prendrons pas de matchs amicaux jusqu&rsquo;au week-end du 15 novembre inclus. Les conditions de match (1 seul adulte accompagnant, pas de vestiaires) nous semblent trop inconfortables.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Les conditions sanitaires seront strictement observ\u00e9es sur le site du RCS Lens.<\/div>\n<div dir=\"auto\">PRIORITE AU SPORT ET A LA SANTE , OBJECTIF EQUILIBRE DES ENFANTS.<\/div>\n<div id=\"ConnectiveDocSignExtentionInstalled\"><\/div>\n<div id=\"ConnectiveDocSignExtentionInstalled\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Du 1 novembre au 15 novembre: ENTRAINEMENTS : Suite aux derni\u00e8res d\u00e9cisions politiques et sportives, le RCS Lens continuera d&rsquo;assurer les entrainements (mercredi et vendredi) pour les joueurs des cat\u00e9gories U8, U10 et U12, \u00e0 condition qu&rsquo;un nombre suffisant de joueurs assistent aux s\u00e9ances. Nous vous rappelons l&rsquo;importance d&rsquo;avertir le coach de la pr\u00e9sence ou [&hellip;]<\/p>\n","protected":false},"template":"","class_list":["post-541","news","type-news","status-publish","hentry","newscat-lastnews","newscat-homepage"],"_links":{"self":[{"href":"https:\/\/www.footclubs.be\/cslens\/wp-json\/wp\/v2\/api-news\/541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.footclubs.be\/cslens\/wp-json\/wp\/v2\/api-news"}],"about":[{"href":"https:\/\/www.footclubs.be\/cslens\/wp-json\/wp\/v2\/types\/news"}],"wp:attachment":[{"href":"https:\/\/www.footclubs.be\/cslens\/wp-json\/wp\/v2\/media?parent=541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}